{"id":120,"count":57,"description":"","link":"https:\/\/saonaisland.com.do\/jv\/product-category\/fees-entrace\/","name":"Fees entrace","slug":"fees-entrace","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/saonaisland.com.do\/jv\/wp-json\/wp\/v2\/product_cat\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saonaisland.com.do\/jv\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/saonaisland.com.do\/jv\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/saonaisland.com.do\/jv\/wp-json\/wp\/v2\/product?product_cat=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}