{"id":546,"date":"2020-06-15T15:29:37","date_gmt":"2020-06-15T15:29:37","guid":{"rendered":"https:\/\/haitises.com\/?post_type=product&#038;p=546"},"modified":"2024-04-19T14:24:18","modified_gmt":"2024-04-19T14:24:18","slug":"parque-nacional-los-haitises-y-playa-rincon","status":"publish","type":"product","link":"https:\/\/saonaisland.com.do\/eo\/saona\/parque-nacional-los-haitises-y-playa-rincon\/","title":{"rendered":"Parque Nacional Los Haitises y Playa Rinc\u00f3n"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><em>Cuevas, manglares, almuerzo y nataci\u00f3n en la playa<\/em><\/p>\n<h2>Parque Nacional Los Haitises y Playa el Rinc\u00f3n<\/h2>\n<h3>Priskribo<\/h3>\n<p>Parque Nacional Los Haitises y Playa El Rinc\u00f3n con almuerzo en la playa. Ven con nosotros y visita el parque nacional m\u00e1s hermoso de Rep\u00fablica Dominicana, visitando manglares, cuevas y la bah\u00eda de San Lorenzo. Despu\u00e9s de regresar al puerto de Saman\u00e1 para hacer un viaje privado a Playa El Rinc\u00f3n con almuerzo en la playa.<\/p>\n<p>Despu\u00e9s de esta experiencia, tendr\u00e1 su tiempo en la playa adem\u00e1s de un almuerzo local en la playa.<\/p>\n<ul>\n<li>Incluye almuerzo buffet en la playa.<\/li>\n<li>Tasas inclu\u00eddas<\/li>\n<li>La gvidilo disponigas instrukcion kaj superrigardon.<\/li>\n<\/ul>\n<h3>Inkludoj kaj ekskludoj<\/h3>\n<h4>Inkluzivecoj<\/h4>\n<ol>\n<li>almuerzo en la playa<\/li>\n<li>Tour Los Haitises + Playa El Rinc\u00f3n<\/li>\n<li>\u0108iuj impostoj, kotizoj kaj pritraktadoj.<\/li>\n<li>Lokaj impostoj<\/li>\n<li>Trinka\u0135oj<\/li>\n<li>\u0108iuj agadoj<\/li>\n<li>Loka gvidisto<\/li>\n<\/ol>\n<h4>Ekskludoj<\/h4>\n<ol>\n<li>Konsiletoj<\/li>\n<li>Transporto<\/li>\n<li>Alkoholaj trinka\u0135oj<\/li>\n<\/ol>\n<h3><em>Foriro kaj reveno<\/em><\/h3>\n<p>La voja\u011danto ricevos renkontpunkton post la rezerva procezo. Ekskursoj komenci\u011das kaj fini\u011das \u0109e niaj renkontpunktoj.<\/p>\n<h3><em>Kion atendi?<\/em><\/h3>\n<p>Obtenga sus boletos para visitar el Parque Nacional Los Haitises con un maravilloso almuerzo en Playa El Rinc\u00f3n.<\/p>\n<p>El recorrido, organizado por \u00abBooking Adventures\u00bb, comienza en el punto de encuentro establecido con el gu\u00eda tur\u00edstico.<\/p>\n<p>Haremos un recorrido en bote por la bah\u00eda de Saman\u00e1 para visitar el Parque Nacional Los Haitises, pasando por manglares, por antiguas cuevas piratas y en bosques protegidos en esta pintoresca reserva.<br \/>\nVen con Booking Adventures y comienza a observar algunos manglares llenos de p\u00e1jaros, colinas onduladas de exuberante vegetaci\u00f3n y cuevas del Parque Nacional Los Haitises. Tomando un barco, Excursi\u00f3n desde el puerto de Saman\u00e1.<\/p>\n<p>El nombre del parque nacional proviene de sus habitantes originales, los indios ta\u00ednos. En su idioma, \u00abHaitises\u00bb se traduce en tierras altas o colinas, una referencia a las empinadas formaciones geol\u00f3gicas de la costa con calizas. Avent\u00farate en el parque para explorar cuevas como la Cueva de la Arena y la Cueva de la L\u00cdnea. Las cuevas en la reserva fueron utilizadas como refugio por los indios ta\u00ednos y, m\u00e1s tarde, por los piratas escondidos. Busque dibujos de indios que decoran algunas de las paredes.<\/p>\n<p>Despu\u00e9s de visitar el Parque Nacional Los Haitises, tomaremos el bote y atravesaremos los manglares y llegaremos a la bah\u00eda abierta de San Lorenzo directamente al puerto de Saman\u00e1. En el puerto de Saman\u00e1, tomamos nuestro transporte privado a la playa de El Rinc\u00f3n para almorzar.<\/p>\n<p>El almuerzo ser\u00e1 delicioso pero a\u00fan no terminamos. Despu\u00e9s del almuerzo, tendr\u00e1 tiempo para disfrutar de la playa o simplemente sentarse a la sombra y disfrutar de Pi\u00f1a Colada o Coco Loco en uno de los t\u00edpicos bares dominicanos. Alrededor de las 4:30 pm saliendo de la playa y regresando a Saman\u00e1.<\/p>\n<p>En la playa y puedes quedarte todo el tiempo que quieras nadando. Se ofrecen Pescado frito y Tostones! Si eres vegano, tambi\u00e9n podemos prepararte algo de comida.<\/p>\n<h3><em>Kion vi alportu?<\/em><\/h3>\n<ul>\n<li>Fotilo<\/li>\n<li>Forpu\u015drimedoj<\/li>\n<li>sunkremo<\/li>\n<li>\u0108apelo<\/li>\n<li>Komfortaj pantalonoj<\/li>\n<li>Arbaraj pied\u015duoj<\/li>\n<li>Sandalias a la playa<\/li>\n<li>Vestido nadador<\/li>\n<\/ul>\n<h3><em>Repreno de hotelo<\/em><\/h3>\n<p>Hotel-kolektado ne estas ofertita por \u0109i tiu turneo.<\/p>\n<p><strong>Nota<\/strong>: si realiza la reserva dentro de las 24 horas de la hora de salida del tour \/ excursi\u00f3n, podemos organizar la recogida en el hotel con cargos adicionales. Una vez que se complete su compra, le enviaremos informaci\u00f3n de contacto completa (n\u00famero de tel\u00e9fono, direcci\u00f3n de correo electr\u00f3nico, etc.) para que nuestro gu\u00eda tur\u00edstico local organice los arreglos de recogida.<\/p>\n<h3><em>Konfirmo de pliaj informoj<\/em><\/h3>\n<ul>\n<li>La biletoj estas la Kvitanco post pagado por \u0109i tiu Turneo. Vi povas montri la pagon per via telefono.<\/li>\n<li>La renkontpunkto estos ricevita post la rezerva procezo.<\/li>\n<li>Infanoj devas esti akompanataj de plenkreskulo.<\/li>\n<li>Ne alirebla por rulse\u011do<\/li>\n<li>Los infantes deben sentarse en el regazo<\/li>\n<li>Ne rekomendita por voja\u011dantoj kun dorsaj problemoj.<\/li>\n<li>No recomendado para viajeros embarazadas.<\/li>\n<li>Neniuj koraj problemoj a\u016d aliaj seriozaj malsanoj.<\/li>\n<li>Plej multaj voja\u011dantoj povas partopreni.<\/li>\n<\/ul>\n<h3><em>Politiko pri nuligo<\/em><\/h3>\n<p>Por plena repago, nuligi almena\u016d 24 horojn anta\u016d la komencdato de la sperto.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Parque Nacional Los Haitises y Playa El Rinc\u00f3n con almuerzo en la playa. Ven con nosotros y visita el parque nacional m\u00e1s hermoso de la Rep\u00fablica Dominicana, visitando manglares, cuevas y la bah\u00eda de San Lorenzo. Despu\u00e9s de regresar al puerto de Saman\u00e1 para hacer un viaje privado a Playa El Rinc\u00f3n con almuerzo en la playa.<\/p>\n<p>Consigue tus entradas con ofertas aqu\u00ed &#8230;<\/p>\n<p>Por favor seleccione la fecha para el Tour<\/p>","protected":false},"featured_media":227,"template":"","meta":[],"product_brand":[],"product_cat":[433,443],"product_tag":[138,195,196,142,147,148,143],"class_list":{"0":"post-546","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-excursiones-privadas","7":"product_cat-tours-y-excursiones-es","8":"product_tag-beach-time","9":"product_tag-el-rincon-beach","10":"product_tag-playa-el-rincon","11":"product_tag-samana","12":"product_tag-samana-bay","13":"product_tag-samana-excursions","14":"product_tag-samana-tours","16":"first","17":"instock","18":"sale","19":"sold-individually","20":"shipping-taxable","21":"product-type-external"},"_links":{"self":[{"href":"https:\/\/saonaisland.com.do\/eo\/wp-json\/wp\/v2\/product\/546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saonaisland.com.do\/eo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/saonaisland.com.do\/eo\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saonaisland.com.do\/eo\/wp-json\/wp\/v2\/media\/227"}],"wp:attachment":[{"href":"https:\/\/saonaisland.com.do\/eo\/wp-json\/wp\/v2\/media?parent=546"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/saonaisland.com.do\/eo\/wp-json\/wp\/v2\/product_brand?post=546"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/saonaisland.com.do\/eo\/wp-json\/wp\/v2\/product_cat?post=546"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/saonaisland.com.do\/eo\/wp-json\/wp\/v2\/product_tag?post=546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}